{"id":43293,"date":"2015-09-01T08:34:08","date_gmt":"2015-09-01T06:34:08","guid":{"rendered":"http:\/\/www.radiobeton.com\/wordpress\/?p=43293"},"modified":"2015-09-01T08:34:08","modified_gmt":"2015-09-01T06:34:08","slug":"portishead-dummy","status":"publish","type":"post","link":"https:\/\/www.radiobeton.com\/www\/portishead-dummy\/","title":{"rendered":"PORTISHEAD &#8211; Dummy"},"content":{"rendered":"<h2>Aujourd&rsquo;hui je vous parle de <strong> <em>Dummy<\/em> <\/strong>, 1er album du groupe anglais <strong>Portishead<\/strong>, compos\u00e9 de Geoff Barrow &#038; Beth Gibbons, sorti en 1994 sur le label Go!Beat.<\/h2>\n<p>Avec l&rsquo;album <em>Nevermind <\/em> de Nirvana et <em>Californication <\/em> des Red Hot, d\u00e9j\u00e0 chroniqu\u00e9s dans le Lundispensable, <strong>Dummy <\/strong> est un autre de ces albums qui me renvoient directement \u00e0 mes ann\u00e9es lyc\u00e9e. Autant dire que je l&rsquo;ai d\u00e9couvert longtemps apr\u00e8s sa sortie puisque je n&rsquo;avais alors que 6 ans. Je me souviens encore d&rsquo;\u00e9couter en boucle certains des morceaux lorsque j&rsquo;avais envie de calme, les \u00e9couteurs bien viss\u00e9s dans mes oreilles ou alors bien fort dans ma chambre d&rsquo;adolescente pour montrer \u00e0 mes parents que j&rsquo;\u00e9tais d\u00e9prim\u00e9e. P\u00e9riode adolescence je vous ai dit.<\/p>\n<p>Sur cet album, 11 titres avec quasiment que des tubes qui ont \u00e9t\u00e9 encens\u00e9s par les critiques et qui sont consid\u00e9r\u00e9s comme la base du mouvement Trip Hop, m\u00eame si on reconna\u00eet des similarit\u00e9s avec leurs voisins de Bristol, Massive Attack.<br \/>\nUne musique influenc\u00e9e par le hip hop, le scratch, le jazz et la soul, c&rsquo;est \u00e7a le trip hop. Et avec Portishead, alors que les beats lents et lourds de Geoff Barrow m\u00eal\u00e9s de scratches et de samples nous attirent vers un univers noir et triste, la belle voix de Beth Gibbons, \u00e0 la fois \u00e9raill\u00e9e, fragile, envo\u00fbtante, sensuelle et touchante, nous entra\u00eene elle, vers des hauteurs plus lumineuses. <\/p>\n<p>L&rsquo;album commence fort avec le titre <em>Mysterons<\/em>. D\u00e8s les premi\u00e8res notes, il nous met directement dans l&rsquo;ambiance g\u00e9n\u00e9rale et on se sent d\u00e9connect\u00e9 du reste du monde.<br \/>\nAvec les deux morceaux suivants, <em>Sour times<\/em> et <em>Strangers <\/em> notre amour pour Portishead ne fait que grandir jusqu&rsquo;\u00e0 <em>It could be sweet<\/em> o\u00c3\u00b9 le groupe nous d\u00e9voile quelque chose de plus doux, loin de cette noirceur qui entoure beaucoup de morceaux et o\u00c3\u00b9 la chanteuse nous enveloppe de sa magnifique voix jusqu&rsquo;\u00e0 nous faire frissonner.<br \/>\nLes amoureux du scratch sont servis avec le morceau suivant, <em>Wandering Star<\/em>, puis une petite pause de tendresse sucr\u00e9e avec <em>It&rsquo;s a fire<\/em>, et \u00e7a reprend de plus belle avec le tube <em>Numb<\/em><br \/>\nEnsuite c&rsquo;est <em>Roads<\/em>, ce tube est tellement beau qu&rsquo;on pourrait en pleurer, si on n&rsquo;avait d\u00e9j\u00e0 craqu\u00e9 sur les 7 premiers morceaux.<br \/>\nSur <em>Pedestral<\/em>, Beth Gibbons pose sa voix en chuchotement sur un beat profond et un air jazz hip-hop avec du saxophone et des scratches. Et sur <strong>Biscuit <\/strong> ils utilisent un son old school de vieux vinyle en fond.<br \/>\nEnfin, l&rsquo;album termine sur un chef d&rsquo;\u00c5\u201cuvre, <em>Glory box<\/em>, bien s\u00fbr mon titre pr\u00e9f\u00e9r\u00e9 de cet album.<\/p>\n<p>Avec <em> <strong>Dummy<\/strong> <\/em>, et surtout ce tube <em>Glory Box<\/em>, <strong>Portishead <\/strong> sonne le renouveau de la cr\u00e9ation musicale britannique, et un coup dans les dents \u00e0 la brit pop des Blur, Oasis et autres groupes du genre !<\/p>\n<p><strong> <em>Dummy<\/em> <\/strong>, c&rsquo;est l&rsquo;indispensable du trip hop, \u00e0 avoir absolument dans sa discoth\u00e8que.<br \/>\nC&rsquo;est s\u00fbr que c&rsquo;est pas l&rsquo;album \u00e0 mettre en soir\u00e9e pour s&rsquo;ambiancer et aller danser, mais versez-vous un verre de vin, \u00e9teignez les lumi\u00e8res, allumez quelque bougies, et lancez l&rsquo;album : une soir\u00e9e parfaite !<\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/t3baifH7bhI?rel=0\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui je vous parle de Dummy , 1er album du groupe anglais Portishead, compos\u00e9 de Geoff Barrow &#038; Beth Gibbons, sorti en 1994 sur le label Go!Beat. Avec l&rsquo;album Nevermind de Nirvana et Californication des Red Hot, d\u00e9j\u00e0 chroniqu\u00e9s dans le Lundispensable, Dummy est un autre de ces albums qui me renvoient directement \u00e0 mes &hellip; <a href=\"https:\/\/www.radiobeton.com\/www\/portishead-dummy\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;PORTISHEAD &#8211; Dummy&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":43292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[280],"tags":[],"class_list":["post-43293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-lundispensable"],"_links":{"self":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/43293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/comments?post=43293"}],"version-history":[{"count":0,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/43293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media\/43292"}],"wp:attachment":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media?parent=43293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/categories?post=43293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/tags?post=43293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}