{"id":55723,"date":"2016-04-26T18:24:30","date_gmt":"2016-04-26T16:24:30","guid":{"rendered":"http:\/\/www.radiobeton.com\/wordpress\/?p=55723"},"modified":"2016-04-26T18:24:30","modified_gmt":"2016-04-26T16:24:30","slug":"brain-damage-ashes-to-ashes-dub-to-dub","status":"publish","type":"post","link":"https:\/\/www.radiobeton.com\/www\/brain-damage-ashes-to-ashes-dub-to-dub\/","title":{"rendered":"BRAIN DAMAGE : Ashes to ashes &#8211; dub to dub"},"content":{"rendered":"<p>Aujourd&rsquo;hui, le lundispensable, c&rsquo;est cet album de Brain Damage : Ashes to ashes &#8211; dub to dub.<br \/>\nApr\u00e8s le maxi Bipolar disorder, sorti en 99 sur leur propre label Bangarang, Ashes to ashes &#8211; dub to dub, sorte de concept album, donne au duo st\u00e9phanois l&rsquo;occasion de montrer que le dub n&rsquo;est pas rest\u00e9 coinc\u00e9 entre Kingston et Londres, mais qu&rsquo;il a au contraire bien pris racine, que ce soit entre les murs de b\u00e9ton des teufs o\u00c3\u00b9 se d\u00e9pose le Brain Damage sound-system ou entre les parois feutr\u00e9es des studios de Jarring Effects.<\/p>\n<p>Martin Nathan, digne successeur de King Tubby et de ses productions l\u00e9ch\u00e9es, \u00e9tait \u00e0 l&rsquo;\u00e9poque encore accompagn\u00e9 de Rapha\u00ebl Talis \u00e0 la basse. Le duo Brain Damage a bien s\u00fbr assimil\u00e9 tout le renouveau de la sc\u00e8ne dub.<br \/>\nCe genre musical b\u00c3\u00a2tard, consid\u00e9r\u00e9 comme un simple \u00e2\u20ac\u0153remixage\u00e2\u20ac\u009d de titres reggae, m\u00eame quand il est pratiqu\u00e9 par des g\u00e9nies tels que King Tubby, aura eu du mal \u00e0 se faire une place dans le spectre des musiques dites \u00e2\u20ac\u0153actuelles\u00e2\u20ac\u009d. Rang\u00e9 entre \u00e2\u20ac\u0153\u00e9lectro\u00e2\u20ac\u009d, \u00e2\u20ac\u0153reggae\u00e2\u20ac\u009d et \u00e2\u20ac\u0153dancehall\u00e2\u20ac\u009d, il faut finalement attendre la vague venue d&rsquo;Angleterre dans les ann\u00e9es 90 pour que le dub se fasse une place dans le paysage des musiques \u00e9lectroniques en France, avec des artistes tels que Treponem Pal, mais aussi High Tone, Zenzile, et le soutien pr\u00e9cieux des labels Bangarang et Jarring Effects, pionniers en la mati\u00e8re.<br \/>\nL&rsquo;album Ashes to ashes &#8211; dub to dub, qui pr\u00e9c\u00e8de Spoken dub manifesto, est compos\u00e9 de deux parties distinctes, les cinq derniers titres \u00e9tant des reprises dub des cinq premiers. <\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/_UoCinAzXV8\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Sur cet album, on sent aussi toute l&rsquo;influence de Linton Kwesi Johnson, pilier de la dub poetry : En composant avec des textes de l&rsquo;activiste Hakim Bey, du chanteur reggae Leeroy Green ou de l&rsquo;artiste Black Sifichi, qui vient poser la voix la plus salement \u00e9raill\u00e9e de la Dub poetry, sur les titres The Unity Of The Circle, et The Balance Of The Cube, Martin Nathan et Rapha\u00ebl Talis parviennent finalement \u00e0 utiliser la voix humaine comme une mati\u00e8re sp\u00e9cifique et vont creuser dans le timbre et le souffle la texture sonore qui compose cet album.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/A9RzZXaFmVk\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Sur Ashes to Ashes &#8211; Dub to Dub, les titres sont successivement repris, r\u00e9interpr\u00e9t\u00e9s, remix\u00e9s et te transportent dans un univers sombre, glauque, entre une ambiance de science-fiction et des sonorit\u00e9s lourdes, comme sur cette version dub de The Unity Of The Circle :<\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/MM_OEN7gP2I\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Brain Damage s&rsquo;insinue dans ton cerveau et vient r\u00e9pandre un son lancinant, port\u00e9 par de lourdes basses et illumin\u00e9 par \u00e9clairs harmoniques de violons.<br \/>\nBref, il serait temps d&rsquo;\u00e9teindre les lumi\u00e8res, de s&rsquo;installer confortablement et de se laisser emporter. N&rsquo;aies pas peur,  bon voyage !<\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/JWJnrSlyTso\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, le lundispensable, c&rsquo;est cet album de Brain Damage : Ashes to ashes &#8211; dub to dub. Apr\u00e8s le maxi Bipolar disorder, sorti en 99 sur leur propre label Bangarang, Ashes to ashes &#8211; dub to dub, sorte de concept album, donne au duo st\u00e9phanois l&rsquo;occasion de montrer que le dub n&rsquo;est pas rest\u00e9 coinc\u00e9 &hellip; <a href=\"https:\/\/www.radiobeton.com\/www\/brain-damage-ashes-to-ashes-dub-to-dub\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;BRAIN DAMAGE : Ashes to ashes &#8211; dub to dub&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":55722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[280],"tags":[],"class_list":["post-55723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-lundispensable"],"_links":{"self":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/55723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/comments?post=55723"}],"version-history":[{"count":0,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/55723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media\/55722"}],"wp:attachment":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media?parent=55723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/categories?post=55723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/tags?post=55723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}