{"id":58809,"date":"2017-01-23T17:51:00","date_gmt":"2017-01-23T16:51:00","guid":{"rendered":"http:\/\/www.radiobeton.com\/wordpress\/?p=58809"},"modified":"2017-01-23T17:51:00","modified_gmt":"2017-01-23T16:51:00","slug":"wiley-godfather","status":"publish","type":"post","link":"https:\/\/www.radiobeton.com\/www\/wiley-godfather\/","title":{"rendered":"WILEY : Godfather"},"content":{"rendered":"<p><strong>Mr ESKIBOI<\/strong>, le talentueux MC d&rsquo;Angleterre, et un des personnages les plus influents du pays (dixit BBC), pose son regard en N&#038;B tel l&rsquo;esprit de son <em>Evolve Or Be Extinct<\/em> en 2012, qui \u00e9tait d\u00e9j\u00e0 fa\u00e7onn\u00e9 par son regard per\u00e7ant sur notre temps, sans \u00eatre en comp\u00e9tition. <\/p>\n<p><iframe loading=\"lazy\" width=\"480\" height=\"359\" src=\"https:\/\/www.youtube.com\/embed\/sa1glDxNvfk\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>&#8230; sauf que l\u00e0, \u00e7a sent la fin de carri\u00e8re (Il a d\u00e9cid\u00e9 que <em>Godfather<\/em> serait son dernier album), et comme si c&rsquo;\u00e9tait ses derniers instants avant de perdre la vie, il donne TOUT dans son domaine, qu&rsquo;il connait par coeur : le <strong>GRIME<\/strong>, ou le <strong>ESKIBEAT<\/strong>, ou un m\u00e9lange de tout \u00e7a. Car Wiley est un bon blagueur et ironise sa musique, tout en \u00e9tant tr\u00e8s pro. Au d\u00e9but de sa carri\u00e8re, les journalistes ne savaient plus o\u00c3\u00b9 mettre les oreilles, sur les manifestes d&rsquo;un son rugueux tel que le <em>Boy In Da Corner<\/em> de <strong>Dizzee Rascal <\/strong> (2003) et <em>Treddin&rsquo; On Thin Ice<\/em> de <strong>Wiley<\/strong> (2004), deux p\u00e9tages de c\u00c3\u00a2ble soumis \u00e0 aucune r\u00e8gle. Le morceau <a href=\"https:\/\/www.youtube.com\/watch?v=D8PeDsO0vGo\"><em>Wot Do U Call It?<\/em><\/a> est d&rsquo;ailleurs un bon exemple de l&rsquo;esprit totalement in\u00e9dit d&rsquo;un son qu&rsquo;on nommera donc GRIME. <\/p>\n<p>Treize ans sont pass\u00e9s depuis son premier album, avec plus ou moins de r\u00e9ussite \u00e0 force de toucher \u00e0 tout par la suite (Dance ; Electro-House &#8230;), mais force est de constater que son flow reste le m\u00eame. <strong>C&rsquo;est un cam\u00e9l\u00e9on<\/strong>, pr\u00eat \u00e0 tout pour remplir sa mission : <\/p>\n<p><strong>Rester coh\u00e9rent et authentique<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" width=\"480\" height=\"150\" src=\"https:\/\/www.youtube.com\/embed\/tReqL6gE_74\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p><strong>GODFATHER<\/strong> n&rsquo;est pas un titre racoleur et pr\u00e9tentieux. Il remet les pendules \u00e0 l&rsquo;heure et joue au malin plaisir d&rsquo;\u00eatre le prof du mouvement. Du coup, il y a beaucoup d&rsquo;invit\u00e9s (pas de femmes, c&rsquo;est bien dommage, Lady Leshurr where are you ?) comme des v\u00e9t\u00e9rans <strong>JME<\/strong> ; Newham Generals &#038; Flowdan, mais aussi les premiers de la classe comme <strong>Skepta<\/strong> ; Breeze ; Manga &#8230; Donc stop, maintenant le mec n&rsquo;a plus l&rsquo;\u00c3\u00a2ge de faire mumuse dans la cour de r\u00e9cr\u00e9 des Wack MC&rsquo;s, il s\u00e9lectionne les meilleurs producteurs du Grime et offre modestement un monument de l&rsquo;Angleterre sale et crasseuse, qui n&rsquo;a pas besoin de lui faire la morale. BANG BANG BANG. <strong>Un prochain classique dans ta collection<\/strong>. <\/p>\n<p><a href=\"https:\/\/www.facebook.com\/OfficialWiley\/?fref=ts\">SOCIAL<\/a> \/ <a href=\"https:\/\/bleep.com\/release\/76689-wiley-godfather\">ACHETER<\/a> \/ <a href=\"https:\/\/www.discogs.com\/fr\/artist\/197311-Wiley-2\">DISCOGS<\/a> \/ <a href=\"https:\/\/open.spotify.com\/album\/1F4VaFhSDTVK5uDPXbm42l\">SPOTIFY<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mr ESKIBOI, le talentueux MC d&rsquo;Angleterre, et un des personnages les plus influents du pays (dixit BBC), pose son regard en N&#038;B tel l&rsquo;esprit de son Evolve Or Be Extinct en 2012, qui \u00e9tait d\u00e9j\u00e0 fa\u00e7onn\u00e9 par son regard per\u00e7ant sur notre temps, sans \u00eatre en comp\u00e9tition. &#8230; sauf que l\u00e0, \u00e7a sent la fin &hellip; <a href=\"https:\/\/www.radiobeton.com\/www\/wiley-godfather\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;WILEY : Godfather&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":58808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[196],"tags":[],"class_list":["post-58809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-disque-de-la-semaine"],"_links":{"self":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/58809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/comments?post=58809"}],"version-history":[{"count":0,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/58809\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media\/58808"}],"wp:attachment":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media?parent=58809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/categories?post=58809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/tags?post=58809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}