{"id":60212,"date":"2017-05-04T11:52:16","date_gmt":"2017-05-04T09:52:16","guid":{"rendered":"http:\/\/www.radiobeton.com\/wordpress\/?p=60212"},"modified":"2017-05-04T11:52:16","modified_gmt":"2017-05-04T09:52:16","slug":"megadeth-rust-in-peace","status":"publish","type":"post","link":"https:\/\/www.radiobeton.com\/www\/megadeth-rust-in-peace\/","title":{"rendered":"MEGADETH &#8211; RUST IN PEACE"},"content":{"rendered":"<p>J&rsquo;ai commenc\u00e9 \u00e0 \u00e9couter du metal quand j&rsquo;avais 11 ans, du Power et du Speed metal essentiellement.<\/p>\n<p>Et puis un jour j&rsquo;ai atteints une chose horrible : la pubert\u00e9.<\/p>\n<p>J&rsquo;\u00e9tais en col\u00e8re contre tout et tout le monde, j&rsquo;avais abandonn\u00e9 le violon au grand d\u00e9sespoir de mes parents, #r\u00e9bellion, et je venais de me mettre \u00e0 \u00e9couter du thrash avec les premiers albums de Metallica.<\/p>\n<p>Puis ma col\u00e8re diminua progressivement. Lentement mais s\u00fbrement j&rsquo;atteignais l&rsquo;\u00c3\u00a2ge adulte.<\/p>\n<p>Un beau jour, mon prof de gratte me regarda tr\u00e8s s\u00e9rieusement et me dit \u00c2\u00ab Robin, on va faire du Megadeth \u00c2\u00bb.<\/p>\n<p>Alors \u00e9videmment je connaissais le groupe, de loin, mais je n&rsquo;avais jusqu&rsquo;alors jamais rien \u00e9couter d&rsquo;eux.<\/p>\n<p>Mon prof me mit un casque sur les oreilles et balan\u00e7a <em>Hangar 18<\/em>.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/37ECJWbHjoQ\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>A peine rentr\u00e9 chez moi, j&rsquo;achetais le meilleur album de Thrash de tous les temps, l&rsquo;un des meilleurs albums jamais \u00e9crit, l&rsquo;album qui me fit passer d\u00e9finitivement dans l&rsquo;\u00c3\u00a2ge adulte (Bye bye Metallica&#8230;)<\/p>\n<p>Tous les morceaux sans exception \u00e9taient une r\u00e9volution dans mes oreilles. <\/p>\n<p>La perfection, l&rsquo;ultime orgasme auditif, avec la rage, la puissance et l&rsquo;\u00e9nergie d&rsquo;un album qui te fait bouger la t\u00eate instinctivement.<\/p>\n<p>Rien ne pourrait jamais d\u00e9tr\u00f4ner cet album du pi\u00e9destal sur lequel je l&rsquo;avais mis.<\/p>\n<p>Les riffs de guitare, la batterie de <strong>Nick Menza<\/strong>, les solos de <strong>Marty Friedman<\/strong>, Le duo rythmique de <strong>David Ellefson<\/strong> et du dieu <strong>Dave Mustaine<\/strong>, rien ne m&rsquo;avait jamais pr\u00e9par\u00e9 \u00e0 \u00e7a.<\/p>\n<p>Surtout pas \u00e0 l&rsquo;un des plus beaux solos qu&rsquo;il m&rsquo;ait \u00e9t\u00e9 donn\u00e9 d&rsquo;\u00e9couter.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/blFCMpd6AG4\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>A l&rsquo;instant c&rsquo;\u00e9tait <em>Tornado of Souls<\/em>, et tout de suite si vous n&rsquo;\u00eates toujours pas convaincu, avant de se quitter, voici le morceau \u00e9ponyme de l&rsquo;album : <em>Rust in Peace&#8230; Polaris<\/em>.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/70eQZCdcPFY\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai commenc\u00e9 \u00e0 \u00e9couter du metal quand j&rsquo;avais 11 ans, du Power et du Speed metal essentiellement. Et puis un jour j&rsquo;ai atteints une chose horrible : la pubert\u00e9. J&rsquo;\u00e9tais en col\u00e8re contre tout et tout le monde, j&rsquo;avais abandonn\u00e9 le violon au grand d\u00e9sespoir de mes parents, #r\u00e9bellion, et je venais de me mettre &hellip; <a href=\"https:\/\/www.radiobeton.com\/www\/megadeth-rust-in-peace\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;MEGADETH &#8211; RUST IN PEACE&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":60211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[280],"tags":[],"class_list":["post-60212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-lundispensable"],"_links":{"self":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/60212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/comments?post=60212"}],"version-history":[{"count":0,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/60212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media\/60211"}],"wp:attachment":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media?parent=60212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/categories?post=60212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/tags?post=60212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}