{"id":61159,"date":"2017-08-29T05:48:57","date_gmt":"2017-08-29T03:48:57","guid":{"rendered":"http:\/\/www.radiobeton.com\/wordpress\/?p=61159"},"modified":"2017-08-29T05:48:57","modified_gmt":"2017-08-29T03:48:57","slug":"overhead-silent-witness","status":"publish","type":"post","link":"https:\/\/www.radiobeton.com\/www\/overhead-silent-witness\/","title":{"rendered":"Overhead &#8211; Silent Witness"},"content":{"rendered":"<p>Overhead est un groupe que j&rsquo;ai d\u00e9couvert compl\u00e8tement par hasard. A une \u00e9poque o\u00c3\u00b9 je pratiquais diff\u00e9rents sports de planches, j&rsquo;avais l&rsquo;habitude de visionner des vid\u00e9os de ces sports, et vers 13-14 ans, je suis tomb\u00e9 sur un DVD de glisse (kitesurf et snowkite) qui m&rsquo;a marqu\u00e9. On y voyait par exemple des riders remontant une pente enneig\u00e9e, avec des mouvements d&rsquo;autant plus gracieux qu&rsquo;ils \u00e9taient film\u00e9s au ralenti, et c&rsquo;est le morceau \u00ab\u00a0Air\u00a0\u00bb, d&rsquo;Overhead,  qui les accompagnait.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/5GYT5iQU_dA?ecver=1\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>N&rsquo;ayant pas encore une culture musicale tr\u00e8s \u00e9tendue, j&rsquo;ai \u00e9cout\u00e9 ce groupe un peu en boucle, partout ou j&rsquo;allais, quand je faisais de la longboard ou dans mon lit le soir. Du coup, dans ma m\u00e9moire, Overhead reste associ\u00e9 aux sports de glisse. Il suffit que je r\u00e9\u00e9coute ces morceaux pour me retrouver dix ans en arri\u00e8re et me sentir un peu nostalgique &#8230; Bref &#8230; <\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/WtdLdkH2CSo?ecver=1\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>Le groupe Overhead sort son premier album \u00ab\u00a0Silent Witness\u00a0\u00bb en 2002. C&rsquo;est un album de 11 titres, parfois m\u00e9lancoliques, parfois plus \u00e9nergiques, parfois folks, avec des parties de guitare acoustique accompagn\u00e9es de la voix douce et pure de Nicolas Leroux.<\/p>\n<p>La musique nous invite fortement \u00e0 la r\u00eaverie, aux souvenirs, au voyage &#8230; Je ne trouve pas que l&rsquo;album ait vieilli, et avec le recul je m&rsquo;aper\u00e7ois qu&rsquo;il poss\u00e8de une esth\u00e9tique propre.<br \/>\nJe vous invite, chers auditeurs, \u00e0 finir votre journ\u00e9e en vous isolant un moment chez vous, un verre \u00e0 la main, et \u00e0 chercher sur votre moteur de recherche : Overhead et Silent Witness\u00a0\u00bb. On peut l&rsquo;\u00e9couter en int\u00e9gralit\u00e9 sur Deezer !<\/p>\n<p>Bon voyage<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Overhead est un groupe que j&rsquo;ai d\u00e9couvert compl\u00e8tement par hasard. A une \u00e9poque o\u00c3\u00b9 je pratiquais diff\u00e9rents sports de planches, j&rsquo;avais l&rsquo;habitude de visionner des vid\u00e9os de ces sports, et vers 13-14 ans, je suis tomb\u00e9 sur un DVD de glisse (kitesurf et snowkite) qui m&rsquo;a marqu\u00e9. On y voyait par exemple des riders remontant &hellip; <a href=\"https:\/\/www.radiobeton.com\/www\/overhead-silent-witness\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Overhead &#8211; Silent Witness&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":61158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[280],"tags":[],"class_list":["post-61159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-lundispensable"],"_links":{"self":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/61159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/comments?post=61159"}],"version-history":[{"count":0,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/posts\/61159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media\/61158"}],"wp:attachment":[{"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/media?parent=61159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/categories?post=61159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiobeton.com\/www\/wp-json\/wp\/v2\/tags?post=61159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}